{"id":87,"count":4,"description":"","link":"https:\/\/kennedyhq.com\/wp\/tag\/publishing\/","name":"publishing","slug":"publishing","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>publishing Archives - Kennedy HQ<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"publishing Archives - Kennedy HQ\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kennedyhq.com\/wp\/tag\/publishing\/\" \/>\n<meta property=\"og:site_name\" content=\"Kennedy HQ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/kennedyhq.com\\\/wp\\\/tag\\\/publishing\\\/\",\"url\":\"https:\\\/\\\/kennedyhq.com\\\/wp\\\/tag\\\/publishing\\\/\",\"name\":\"publishing Archives - Kennedy HQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kennedyhq.com\\\/wp\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kennedyhq.com\\\/wp\\\/tag\\\/publishing\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kennedyhq.com\\\/wp\\\/tag\\\/publishing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kennedyhq.com\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"publishing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kennedyhq.com\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/kennedyhq.com\\\/wp\\\/\",\"name\":\"Kennedy HQ\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kennedyhq.com\\\/wp\\\/#\\\/schema\\\/person\\\/aaa2f64793699a4104aaad1976c4b7b3\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kennedyhq.com\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/kennedyhq.com\\\/wp\\\/#\\\/schema\\\/person\\\/aaa2f64793699a4104aaad1976c4b7b3\",\"name\":\"K Kennedy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a5fa375fa98beeeddb3bce81d8ef8591024080ba5bd2058c7995884a19c9389?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a5fa375fa98beeeddb3bce81d8ef8591024080ba5bd2058c7995884a19c9389?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a5fa375fa98beeeddb3bce81d8ef8591024080ba5bd2058c7995884a19c9389?s=96&d=retro&r=g\",\"caption\":\"K Kennedy\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a5fa375fa98beeeddb3bce81d8ef8591024080ba5bd2058c7995884a19c9389?s=96&d=retro&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"publishing Archives - Kennedy HQ","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"publishing Archives - Kennedy HQ","og_url":"https:\/\/kennedyhq.com\/wp\/tag\/publishing\/","og_site_name":"Kennedy HQ","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kennedyhq.com\/wp\/tag\/publishing\/","url":"https:\/\/kennedyhq.com\/wp\/tag\/publishing\/","name":"publishing Archives - Kennedy HQ","isPartOf":{"@id":"https:\/\/kennedyhq.com\/wp\/#website"},"breadcrumb":{"@id":"https:\/\/kennedyhq.com\/wp\/tag\/publishing\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/kennedyhq.com\/wp\/tag\/publishing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kennedyhq.com\/wp\/"},{"@type":"ListItem","position":2,"name":"publishing"}]},{"@type":"WebSite","@id":"https:\/\/kennedyhq.com\/wp\/#website","url":"https:\/\/kennedyhq.com\/wp\/","name":"Kennedy HQ","description":"","publisher":{"@id":"https:\/\/kennedyhq.com\/wp\/#\/schema\/person\/aaa2f64793699a4104aaad1976c4b7b3"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kennedyhq.com\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/kennedyhq.com\/wp\/#\/schema\/person\/aaa2f64793699a4104aaad1976c4b7b3","name":"K Kennedy","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4a5fa375fa98beeeddb3bce81d8ef8591024080ba5bd2058c7995884a19c9389?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a5fa375fa98beeeddb3bce81d8ef8591024080ba5bd2058c7995884a19c9389?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a5fa375fa98beeeddb3bce81d8ef8591024080ba5bd2058c7995884a19c9389?s=96&d=retro&r=g","caption":"K Kennedy"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/4a5fa375fa98beeeddb3bce81d8ef8591024080ba5bd2058c7995884a19c9389?s=96&d=retro&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/kennedyhq.com\/wp\/wp-json\/wp\/v2\/tags\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kennedyhq.com\/wp\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/kennedyhq.com\/wp\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/kennedyhq.com\/wp\/wp-json\/wp\/v2\/posts?tags=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}